{"id":1328,"date":"2020-09-20T18:53:42","date_gmt":"2020-09-20T16:53:42","guid":{"rendered":"http:\/\/www.oedso.at\/web\/?p=1328"},"modified":"2020-09-20T18:53:42","modified_gmt":"2020-09-20T16:53:42","slug":"hallo-dartsportgemeinde","status":"publish","type":"post","link":"https:\/\/www.oedso.at\/web\/news\/hallo-dartsportgemeinde","title":{"rendered":"Hallo Dartsportgemeinde"},"content":{"rendered":"<p><em>Statement der Sport Austria bzgl. der Aus\u00fcbung unseres Sport:<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>*Sg. Damen und Herren,<br \/>\nliebe Kolleginnen und Kollegen!<\/p>\n<p>Lockerungsverordnung: Unklarheit \u00fcber Maximalteilnehmeranzahl 10 Personen indoor<br \/>\nIn der gestrigen Pressekonferenz der Bundesregierung wurde angek\u00fcndigt, die Maximalteilnehmeranzahl von Indoor-Veranstaltungen ohne zugewiesene und gekennzeichnete Sitzpl\u00e4tze auf 10 Personen zu reduzieren. Inwieweit dies den Sportbereich betrifft ist noch unklar, da es hier schlussendlich auf den konkreten Text der Verordnung ankommt und diese noch nicht ver\u00f6ffentlich ist.<br \/>\nSelbstverst\u00e4ndlich setzen wir uns daf\u00fcr ein, dass der Sport im Verein weiterhin m\u00f6glich bleibt. Immerhin hat Sportminister Kogler betont, dass die Ansteckungsgefahr beim Sport verh\u00e4ltnism\u00e4\u00dfig gering und die Umsetzungen der Vereine und Verb\u00e4nde vorbildlich sind. Au\u00dferdem st\u00e4rkt regelm\u00e4\u00dfige Bewegung die Immunabwehr, wodurch auch das Risiko, an einer (viralen) Infektion zu erkranken, reduziert wird.<br \/>\nSobald es hierzu Informationen gibt, finden Sie diese wie gewohnt auf unserer Website\u00a0www.sportaustria.at\/corona<\/p>\n<p>Immer am aktuellsten Stand<br \/>\nBesuchen Sie regelm\u00e4\u00dfig unsere Website und verlinken Sie gerne auf\u00a0www.sportaustria.at\/corona<br \/>\nUnter unseren FAQ finden Sie viele Antworten zu h\u00e4ufig gestellten Fragen. Wir aktualisieren und erweitern die Liste regelm\u00e4\u00dfig. Weiters informieren wir Sie wie bisher \u00fcber Newsletter und WhatsApp; neu bei uns: Facebook und Instagram \u2013 werden Sie Teil der Community:<\/p>\n<p>Facebook:\u00a0www.facebook.com\/bundessportorganisation<\/p>\n<p>Instagram:\u00a0www.instagram.com\/sportaustria<\/p>\n<p>Newsletter:\u00a0www.sportaustria.at\/newsletter<\/p>\n<p>WhatsApp-Infoservice: Nummer 0664 845 43 11 speichern und WhatsApp mit \u201eStart\u201c schicken<\/p>\n<p>Beste Gr\u00fc\u00dfe,<br \/>\nGeorg H\u00f6fner*<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Statement der Sport Austria bzgl. der Aus\u00fcbung unseres Sport: &nbsp; *Sg. Damen und Herren, liebe Kolleginnen und Kollegen! Lockerungsverordnung: Unklarheit \u00fcber Maximalteilnehmeranzahl 10 Personen indoor In der gestrigen Pressekonferenz der Bundesregierung wurde angek\u00fcndigt, die Maximalteilnehmeranzahl von Indoor-Veranstaltungen ohne zugewiesene und gekennzeichnete Sitzpl\u00e4tze auf 10 Personen zu reduzieren. Inwieweit dies den Sportbereich betrifft ist noch unklar, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1328","post","type-post","status-publish","format-standard","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.oedso.at\/web\/wp-json\/wp\/v2\/posts\/1328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oedso.at\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oedso.at\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oedso.at\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oedso.at\/web\/wp-json\/wp\/v2\/comments?post=1328"}],"version-history":[{"count":0,"href":"https:\/\/www.oedso.at\/web\/wp-json\/wp\/v2\/posts\/1328\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oedso.at\/web\/wp-json\/wp\/v2\/media?parent=1328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oedso.at\/web\/wp-json\/wp\/v2\/categories?post=1328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oedso.at\/web\/wp-json\/wp\/v2\/tags?post=1328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}